{"id":5582,"date":"2011-12-19T13:20:34","date_gmt":"2011-12-19T13:20:34","guid":{"rendered":"https:\/\/reindesa.pre.interdigital.biz\/bon-nadal\/"},"modified":"2011-12-19T13:20:34","modified_gmt":"2011-12-19T13:20:34","slug":"bon-nadal","status":"publish","type":"post","link":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/","title":{"rendered":"Bon Nadal"},"content":{"rendered":"<p><a href=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-1014\" title=\"feliznavidad\" src=\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\" alt=\"\" width=\"736\" height=\"1134\" srcset=\"https:\/\/reindesa.pre.interdigital.biz\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg 736w, https:\/\/reindesa.pre.interdigital.biz\/wp-content\/uploads\/2011\/12\/feliznavidad-195x300.jpg 195w, https:\/\/reindesa.pre.interdigital.biz\/wp-content\/uploads\/2011\/12\/feliznavidad-665x1024.jpg 665w, https:\/\/reindesa.pre.interdigital.biz\/wp-content\/uploads\/2011\/12\/feliznavidad-600x924.jpg 600w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[464],"tags":[646,647],"class_list":["post-5582","post","type-post","status-publish","format-standard","hentry","category-piscines-sempre-a-punt","tag-bon-nadal","tag-oferta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bon Nadal - Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bon Nadal - Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\" \/>\n<meta property=\"og:site_name\" content=\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-19T13:20:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reindesa.pre.interdigital.biz\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"736\" \/>\n\t<meta property=\"og:image:height\" content=\"1134\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reindesa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reindesa\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\"},\"author\":{\"name\":\"Reindesa\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\"},\"headline\":\"Bon Nadal\",\"datePublished\":\"2011-12-19T13:20:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\"},\"wordCount\":2,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\",\"keywords\":[\"Bon Nadal\",\"oferta\"],\"articleSection\":[\"Piscines Sempre a Punt\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\",\"url\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\",\"name\":\"Bon Nadal - Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\",\"isPartOf\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\",\"datePublished\":\"2011-12-19T13:20:34+00:00\",\"author\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\"},\"breadcrumb\":{\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage\",\"url\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\",\"contentUrl\":\"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bon Nadal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/#website\",\"url\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/\",\"name\":\"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas\",\"description\":\"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5\",\"name\":\"Reindesa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g\",\"caption\":\"Reindesa\"},\"url\":\"https:\/\/reindesa.pre.interdigital.biz\/ca\/author\/reindesa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bon Nadal - Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/","og_locale":"ca_ES","og_type":"article","og_title":"Bon Nadal - Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","og_url":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/","og_site_name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","article_published_time":"2011-12-19T13:20:34+00:00","og_image":[{"width":736,"height":1134,"url":"https:\/\/reindesa.pre.interdigital.biz\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg","type":"image\/jpeg"}],"author":"Reindesa","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Reindesa"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#article","isPartOf":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/"},"author":{"name":"Reindesa","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5"},"headline":"Bon Nadal","datePublished":"2011-12-19T13:20:34+00:00","mainEntityOfPage":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/"},"wordCount":2,"commentCount":0,"image":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg","keywords":["Bon Nadal","oferta"],"articleSection":["Piscines Sempre a Punt"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/","url":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/","name":"Bon Nadal - Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","isPartOf":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage"},"image":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage"},"thumbnailUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg","datePublished":"2011-12-19T13:20:34+00:00","author":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5"},"breadcrumb":{"@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#primaryimage","url":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg","contentUrl":"http:\/\/www.reindesa.com\/blog\/wp-content\/uploads\/2011\/12\/feliznavidad.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/bon-nadal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/reindesa.pre.interdigital.biz\/ca\/"},{"@type":"ListItem","position":2,"name":"Bon Nadal"}]},{"@type":"WebSite","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/#website","url":"https:\/\/reindesa.pre.interdigital.biz\/ca\/","name":"Reindesa Piscines - Construcci\u00f3n y Mantenimiento de Piscinas","description":"Expertos en piscinas desde 1968 en Barcelona, Girona y Tarragona","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reindesa.pre.interdigital.biz\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/reindesa.pre.interdigital.biz\/ca\/#\/schema\/person\/15c765cfdf3fdd0ad3bdee8ee23af5a5","name":"Reindesa","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d1450929df23d512a42ddb87c6813836e3e2b0d91c67d6b87e67a4ac2355477?s=96&d=mm&r=g","caption":"Reindesa"},"url":"https:\/\/reindesa.pre.interdigital.biz\/ca\/author\/reindesa\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/comments?post=5582"}],"version-history":[{"count":0,"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/posts\/5582\/revisions"}],"wp:attachment":[{"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/media?parent=5582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/categories?post=5582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reindesa.pre.interdigital.biz\/ca\/wp-json\/wp\/v2\/tags?post=5582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}